{"id":9011,"date":"2025-07-15T09:13:15","date_gmt":"2025-07-15T07:13:15","guid":{"rendered":"https:\/\/eu.bd.com\/iv-news\/?p=9011"},"modified":"2025-07-15T09:16:43","modified_gmt":"2025-07-15T07:16:43","slug":"fokus-auf-macova-2025","status":"publish","type":"post","link":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/fokus-auf-macova-2025\/","title":{"rendered":"MACOVA 2025: Zusammen verhindern wir Komplikationen bei Gef\u00e4\u00dfzug\u00e4ngen"},"content":{"rendered":"<p>MACOVA \u2013 Der Multidisziplin\u00e4re Kurs fu\u0308r Gef\u00e4\u00dfzug\u00e4nge \u2013 wurde am Mittwoch, den 11. Juni, in Amsterdam er\u00f6ffnet. Die Veranstaltung brachte 180 Gesundheitsfachkr\u00e4fte aus 28 L\u00e4ndern und 3 Kontinenten zusammen, vereint durch ein gemeinsames Ziel: den Austausch von Wissen und Erfahrungen im Bereich des Gef\u00e4\u00dfzugangsmanagements (Vascular Access Management).<\/p>\n<p><!-- Video link (?) --><\/p>\n<p>Der dreit\u00e4gige Kongress wurde gemeinsam geleitet von Andrew Barton, Pflegeberater fu\u0308r IV-Therapie und Gef\u00e4\u00dfzug\u00e4nge am Frimley Health NHS Trust (UK), und Dr. Fulvio Pinelli, Facharzt fu\u0308r An\u00e4sthesie und Intensivmedizin am Universit\u00e4tsklinikum Careggi in Florenz. Beide Vorsitzenden brachten ihre umfassende Expertise im Bereich VAM ein und sind aktiv in fu\u0308hrenden europ\u00e4ischen Fachgesellschaften fu\u0308r Gef\u00e4\u00dfzug\u00e4nge t\u00e4tig, darunter GaVeCeLT, WoCoVa und NIVAS.<\/p>\n<p>Die Agenda war auf den produktunabh\u00e4ngigen wissenschaftlichen Austausch ausgerichtet, mit dem Ziel, Best Practices beim Gef\u00e4\u00dfzugangsmanagement in der gesamten EMEA-Region zu f\u00f6rdern. Es wurde ein breites Themenspektrum behandelt \u2013 von der Auswahl der am besten geeigneten L\u00f6sung fu\u0308r den Patienten u\u0308ber die Vertiefung in spezifische Therapiegebiete bis hin zum Verst\u00e4ndnis der Pr\u00e4vention und Behandlung von Komplikationen. Auch die Versorgung u\u0308ber das Krankenhaus hinaus, ein wachsendes Interessensfeld fu\u0308r BD und die Gesundheitssysteme in EMEA, wurde thematisiert \u2013 mit einer Pr\u00e4sentation eines virtuellen Krankenhauses im Vereinigten K\u00f6nigreich und der Vorstellung des italienischen Selbstversorgungsmodell HVAS fu\u0308r onkologische Patienten und deren Angeh\u00f6rige.<\/p>\n<p>Zus\u00e4tzlich zu den Vortr\u00e4gen boten Workshops die M\u00f6glichkeit, praktische Erfahrungen mit Ultraschalltechniken und der Sherlock 3CG\u2122-Technologie zur Verfolgung der Katheterspitze zu sammeln. Interaktive Seminare behandelten Themen wie die F\u00f6rderung von Ver\u00e4nderungen im Bereich des Gef\u00e4\u00dfzugangsmanagements, die Auswahl geeigneter L\u00f6sungen und die Sicherheit von medizinischen Fachkr\u00e4ften.<\/p>\n<p><img decoding=\"async\" data-src=\"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2025\/07\/Macova-25-photo.jpg\" alt=\"Macova 2025\" width=\"1420\" height=\"700\" class=\"aligncenter size-full wp-image-9012 lazyload\" style=\"--smush-placeholder-width: 1420px; --smush-placeholder-aspect-ratio: 1420\/700;border-radius:24px\" data-srcset=\"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2025\/07\/Macova-25-photo.jpg 1420w, https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2025\/07\/Macova-25-photo-300x148.jpg 300w, https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2025\/07\/Macova-25-photo-1024x505.jpg 1024w, https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2025\/07\/Macova-25-photo-768x379.jpg 768w, https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2025\/07\/Macova-25-photo-455x224.jpg 455w\" data-sizes=\"(max-width: 1420px) 100vw, 1420px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>MACOVA 2025 knu\u0308pfte an die Geschichte im Bereich des Gef\u00e4\u00dfzugangsmanagements an, die 2008 begann. Die erste MACOVA-Veranstaltung z\u00e4hlte nur 10 Teilnehmende, darunter Dr. Herv\u00e9 Rosay, der seither eine Schlu\u0308sselrolle beim Vorantreiben der Delegation urspru\u0308nglich \u00e4rztlicher Aufgaben an nicht \u00e4rztlichen Gesundheitsfachkr\u00e4ften in Frankreich gespielt hat und seine Erfahrungen auf dem MACOVA 2025 teilte. Wer wei\u00df, was die diesj\u00e4hrigen Teilnehmenden noch alles erreichen werden \u2013 und wie sie gemeinsam mit BD die Praxis in ihren L\u00e4ndern mitgestalten.<\/p>\n<p>Ein Hauptziel des MACOVA ist es, Ver\u00e4nderungen beim Gef\u00e4\u00dfzugangsmanagement in Partnerschaft mit BD voranzutreiben. Um dies zu unterstu\u0308tzen, wurden die Teilnehmenden ermutigt, sich fu\u0308r das VAMbassadors-Programm von BD zu registrieren. Die VAMbassadors sind eine engagierte Gemeinschaft, die sich fu\u0308r Best Practices beim Gef\u00e4\u00dfzugangsmanagement einsetzt und Menschen mit einer gemeinsamen Vision vernetzt, um einen Wandel zu bewirken.<\/p>\n<p>Aber VAMbassador zu sein betrifft nicht nur die 180 Teilnehmenden vom MACOVA \u2013 wir alle haben eine Rolle zu spielen. Auch Sie k\u00f6nnen Teil dieser Gemeinschaft werden und Ihren Beitrag zur Vermeidung von Komplikationen beim Gef\u00e4\u00dfzugang leisten. Als VAMbassador erhalten Sie exklusiven Zugang zu Inhalten, die Sie auf diesem Weg unterstu\u0308tzen \u2013 einschlie\u00dflich aller Materialien vom MACOVA 2025<\/p>\n<p>&nbsp;<br \/>\n<a href=\"https:\/\/eu.bd.com\/iv-news\/de\/registrieren-sie-sich\" target=\"_self\" class=\"click\" rel=\"noopener\"><strong>Ich m\u00f6chte VAMbassador werden<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MACOVA \u2013 Der Multidisziplin\u00e4re Kurs fu\u0308r Gef\u00e4\u00dfzug\u00e4nge \u2013 wurde am Mittwoch, den 11. Juni, in Amsterdam er\u00f6ffnet. Die Veranstaltung brachte&#8230;<\/p>\n","protected":false},"author":10,"featured_media":9013,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[533],"tags":[],"class_list":["post-9011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veranstaltungen-schulung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MACOVA 2025: Zusammen verhindern wir Komplikationen bei Gef\u00e4\u00dfzug\u00e4ngen - BD IV News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/fokus-auf-macova-2025\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MACOVA 2025: Zusammen verhindern wir Komplikationen bei Gef\u00e4\u00dfzug\u00e4ngen - BD IV News\" \/>\n<meta property=\"og:description\" content=\"MACOVA \u2013 Der Multidisziplin\u00e4re Kurs fu\u0308r Gef\u00e4\u00dfzug\u00e4nge \u2013 wurde am Mittwoch, den 11. Juni, in Amsterdam er\u00f6ffnet. Die Veranstaltung brachte...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/fokus-auf-macova-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"BD IV News\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-15T07:13:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-15T07:16:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2025\/07\/MACOVA_2025.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1320\" \/>\n\t<meta property=\"og:image:height\" content=\"708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"willem@pencil-park.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"willem@pencil-park.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/de\\\/veranstaltungen-schulung\\\/fokus-auf-macova-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/de\\\/veranstaltungen-schulung\\\/fokus-auf-macova-2025\\\/\"},\"author\":{\"name\":\"willem@pencil-park.com\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/person\\\/12c13ac1b79e2ccd7db337bf9ae66d57\"},\"headline\":\"MACOVA 2025: Zusammen verhindern wir Komplikationen bei Gef\u00e4\u00dfzug\u00e4ngen\",\"datePublished\":\"2025-07-15T07:13:15+00:00\",\"dateModified\":\"2025-07-15T07:16:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/de\\\/veranstaltungen-schulung\\\/fokus-auf-macova-2025\\\/\"},\"wordCount\":498,\"publisher\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/de\\\/veranstaltungen-schulung\\\/fokus-auf-macova-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/MACOVA_2025.jpg\",\"articleSection\":[\"Veranstaltungen und Schulung\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/de\\\/veranstaltungen-schulung\\\/fokus-auf-macova-2025\\\/\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/de\\\/veranstaltungen-schulung\\\/fokus-auf-macova-2025\\\/\",\"name\":\"MACOVA 2025: Zusammen verhindern wir Komplikationen bei Gef\u00e4\u00dfzug\u00e4ngen - BD IV News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/de\\\/veranstaltungen-schulung\\\/fokus-auf-macova-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/de\\\/veranstaltungen-schulung\\\/fokus-auf-macova-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/MACOVA_2025.jpg\",\"datePublished\":\"2025-07-15T07:13:15+00:00\",\"dateModified\":\"2025-07-15T07:16:43+00:00\",\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/de\\\/veranstaltungen-schulung\\\/fokus-auf-macova-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/de\\\/veranstaltungen-schulung\\\/fokus-auf-macova-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/MACOVA_2025.jpg\",\"contentUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/MACOVA_2025.jpg\",\"width\":1320,\"height\":708,\"caption\":\"MACOVA 2025\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#website\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/\",\"name\":\"BD IV News\",\"description\":\"Your source of information on intravenous therapy, medication delivery and vascular access management.\",\"publisher\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#organization\",\"name\":\"BD IV News\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/BD-Master-Logo-on-Warm-White-512X512px.png\",\"contentUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/BD-Master-Logo-on-Warm-White-512X512px.png\",\"width\":512,\"height\":512,\"caption\":\"BD IV News\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/person\\\/12c13ac1b79e2ccd7db337bf9ae66d57\",\"name\":\"willem@pencil-park.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0d2a26c95a305c130152f9839da84232a6383149ff0ee0a91e707ae3c738209?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0d2a26c95a305c130152f9839da84232a6383149ff0ee0a91e707ae3c738209?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0d2a26c95a305c130152f9839da84232a6383149ff0ee0a91e707ae3c738209?s=96&d=mm&r=g\",\"caption\":\"willem@pencil-park.com\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MACOVA 2025: Zusammen verhindern wir Komplikationen bei Gef\u00e4\u00dfzug\u00e4ngen - BD IV News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/fokus-auf-macova-2025\/","og_locale":"en_GB","og_type":"article","og_title":"MACOVA 2025: Zusammen verhindern wir Komplikationen bei Gef\u00e4\u00dfzug\u00e4ngen - BD IV News","og_description":"MACOVA \u2013 Der Multidisziplin\u00e4re Kurs fu\u0308r Gef\u00e4\u00dfzug\u00e4nge \u2013 wurde am Mittwoch, den 11. Juni, in Amsterdam er\u00f6ffnet. Die Veranstaltung brachte...","og_url":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/fokus-auf-macova-2025\/","og_site_name":"BD IV News","article_published_time":"2025-07-15T07:13:15+00:00","article_modified_time":"2025-07-15T07:16:43+00:00","og_image":[{"width":1320,"height":708,"url":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2025\/07\/MACOVA_2025.jpg","type":"image\/jpeg"}],"author":"willem@pencil-park.com","twitter_card":"summary_large_image","twitter_misc":{"Written by":"willem@pencil-park.com","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/fokus-auf-macova-2025\/#article","isPartOf":{"@id":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/fokus-auf-macova-2025\/"},"author":{"name":"willem@pencil-park.com","@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/person\/12c13ac1b79e2ccd7db337bf9ae66d57"},"headline":"MACOVA 2025: Zusammen verhindern wir Komplikationen bei Gef\u00e4\u00dfzug\u00e4ngen","datePublished":"2025-07-15T07:13:15+00:00","dateModified":"2025-07-15T07:16:43+00:00","mainEntityOfPage":{"@id":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/fokus-auf-macova-2025\/"},"wordCount":498,"publisher":{"@id":"https:\/\/eu.bd.com\/iv-news\/#organization"},"image":{"@id":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/fokus-auf-macova-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2025\/07\/MACOVA_2025.jpg","articleSection":["Veranstaltungen und Schulung"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/fokus-auf-macova-2025\/","url":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/fokus-auf-macova-2025\/","name":"MACOVA 2025: Zusammen verhindern wir Komplikationen bei Gef\u00e4\u00dfzug\u00e4ngen - BD IV News","isPartOf":{"@id":"https:\/\/eu.bd.com\/iv-news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/fokus-auf-macova-2025\/#primaryimage"},"image":{"@id":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/fokus-auf-macova-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2025\/07\/MACOVA_2025.jpg","datePublished":"2025-07-15T07:13:15+00:00","dateModified":"2025-07-15T07:16:43+00:00","inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/fokus-auf-macova-2025\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/fokus-auf-macova-2025\/#primaryimage","url":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2025\/07\/MACOVA_2025.jpg","contentUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2025\/07\/MACOVA_2025.jpg","width":1320,"height":708,"caption":"MACOVA 2025"},{"@type":"WebSite","@id":"https:\/\/eu.bd.com\/iv-news\/#website","url":"https:\/\/eu.bd.com\/iv-news\/","name":"BD IV News","description":"Your source of information on intravenous therapy, medication delivery and vascular access management.","publisher":{"@id":"https:\/\/eu.bd.com\/iv-news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eu.bd.com\/iv-news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/eu.bd.com\/iv-news\/#organization","name":"BD IV News","url":"https:\/\/eu.bd.com\/iv-news\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/logo\/image\/","url":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2024\/04\/BD-Master-Logo-on-Warm-White-512X512px.png","contentUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2024\/04\/BD-Master-Logo-on-Warm-White-512X512px.png","width":512,"height":512,"caption":"BD IV News"},"image":{"@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/person\/12c13ac1b79e2ccd7db337bf9ae66d57","name":"willem@pencil-park.com","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/f0d2a26c95a305c130152f9839da84232a6383149ff0ee0a91e707ae3c738209?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0d2a26c95a305c130152f9839da84232a6383149ff0ee0a91e707ae3c738209?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0d2a26c95a305c130152f9839da84232a6383149ff0ee0a91e707ae3c738209?s=96&d=mm&r=g","caption":"willem@pencil-park.com"}}]}},"lang":"de","translations":{"de":9011,"it":9004,"en":8986},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts\/9011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/comments?post=9011"}],"version-history":[{"count":2,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts\/9011\/revisions"}],"predecessor-version":[{"id":9015,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts\/9011\/revisions\/9015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/media\/9013"}],"wp:attachment":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/media?parent=9011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/categories?post=9011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/tags?post=9011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}