{"id":7492,"date":"2024-04-15T10:40:04","date_gmt":"2024-04-15T08:40:04","guid":{"rendered":"https:\/\/eu.bd.com\/iv-news\/?p=7492"},"modified":"2024-04-15T10:33:45","modified_gmt":"2024-04-15T08:33:45","slug":"la-carenza-di-dispositivi-e-farmaci-in-europa-persiste","status":"publish","type":"post","link":"https:\/\/eu.bd.com\/iv-news\/it\/pubblicazioni-scientifiche\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\/","title":{"rendered":"La carenza di dispositivi e farmaci in Europa persiste"},"content":{"rendered":"<p>I Paesi di tutto il mondo si trovano ad affrontare un&#8217;ampia gamma di sfide nell&#8217;accesso ai prodotti sanitari necessari, come carenze ed esaurimenti.<sup>1 <\/sup>Secondo l&#8217;Organizzazione Mondiale della Sanit\u00e0, si verifica una carenza quando la domanda supera l&#8217;offerta in qualsiasi punto della catena di approvvigionamento.<sup>2<\/sup><\/p>\n<p>Ci\u00f2 pu\u00f2 comportare un esaurimento delle scorte o \u201cla completa assenza di un medicinale, di un prodotto sanitario o di un vaccino nel punto per la dispensazione dei servizi al paziente.\u201d<sup>2 <\/sup>Un sondaggio del 2023 <a href=\"https:\/\/www.eahp.eu\/\">dell\u2019Associazione europea dei farmacisti ospedalieri (EAHP)<\/a> approfondisce il problema della carenza di dispositivi e farmaci a livello regionale. Scopri gli approfondimenti principali di seguito:<\/p>\n<h2>La carenza di farmaci \u00e8 in aumento in Europa?<\/h2>\n<p>L\u2019EAHP ha intervistato 1.497 farmacisti ospedalieri e altri operatori sanitari, pazienti e loro caregiver provenienti da 36 paesi diversi per comprendere meglio le carenze di dispositivi e farmaci negli ospedali europei. Dal sondaggio \u00e8 emerso che il 95% dei farmacisti sta ancora riscontrando carenze di farmaci nel 2023.<sup>3 <\/sup><\/p>\n<p>L&#8217;86% ha riferito di aver riscontrato carenze di farmaci nel 2014, percentuale che \u00e8 salita al 90% nel 2018, al 95% nel 2019 e da allora si \u00e8 stabilizzata.<sup>3 <\/sup>Nel 2022, oltre la met\u00e0 dei farmacisti ha riscontrato carenze di farmaci pi\u00f9 di 10 volte con medicinali di un solo produttore.<sup>3<\/sup><\/p>\n<p>Tra i medicinali pi\u00f9 frequentemente carenti, i farmacisti hanno indicato gli antimicrobici, gli antidolorifici e gli anestetici.<sup>3 <\/sup>Gli intervistati ritenevano che i problemi di produzione, le carenze globali di principi attivi farmaceutici e le sfide della catena di approvvigionamento fossero le cause principali delle carenze di farmaci.<sup>3<\/sup><\/p>\n<p><strong>Ulteriori informazioni su questo argomento: <\/strong><a href=\"https:\/\/eu.bd.com\/iv-news\/it\/novita-e-innovazione\/carenza-di-antibiotici-in-europa-tutto-quello-che-ce-da-sapere\/\">Carenza di antibiotici in Europa: tutto quello che c\u2019\u00e8 da sapere<\/a><\/p>\n<h2>Prevedere la carenza di dispositivi medici<\/h2>\n<p>Il 61% dei farmacisti ospedalieri ha segnalato la carenza di dispositivi medici come un problema nel proprio ospedale, identificando come fattori trainanti i problemi della catena di approvvigionamento e le interruzioni dei componenti dei dispositivi.<sup>3<\/sup><\/p>\n<p>Sappiamo che, a causa di problemi di capacit\u00e0, gli organismi di valutazione della conformit\u00e0 hanno difficolt\u00e0 a certificare\/ricertificare vecchi e nuovi dispositivi medici ai sensi del Regolamento europeo sui dispositivi medici (MDR UE) 2017\/745.<sup>3<\/sup><\/p>\n<p>Ci\u00f2 potrebbe significare che i dispositivi medici sono a rischio di interruzione se non vengono certificati prima della fine del periodo di transizione, che terminer\u00e0 il 31 dicembre 2027 per i dispositivi a rischio pi\u00f9 alto e il 31 dicembre 2028 per i dispositivi a rischio medio e basso.<sup>3 <\/sup>Inoltre, il 71% dei farmacisti ha constatato che i produttori raramente comunicano la carenza di dispositivi, mentre il 2% non riceve mai alcuna notifica.<sup>3<\/sup><\/p>\n<p><strong>Ulteriori informazioni su questo argomento: <\/strong><a href=\"https:\/\/eu.bd.com\/iv-news\/it\/novita-e-innovazione\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\/\">Regolamento dell\u2019Unione Europea sui dispositivi medici (MDR) 2017\/745<\/a><\/p>\n<h2>Che impatto hanno le carenze di dispositivi e farmaci sull&#8217;assistenza al paziente?<\/h2>\n<p>Il 55% dei pazienti intervistati ha riscontrato una carenza di farmaci e il 45% una carenza di dispositivi durante il trattamento; il 37% delle carenze di farmaci, secondo quanto riferito, ha avuto un impatto sull&#8217;assistenza.<sup>3 <\/sup>La maggior parte degli intervistati ha valutato la gravit\u00e0 della carenza di dispositivi e farmaci nel proprio ospedale come moderata o grave, anche se molti l&#8217;hanno valutata come lieve.<sup>3<\/sup><\/p>\n<p>Secondo i risultati del sondaggio, gli impatti pi\u00f9 comunemente segnalati sull&#8217;assistenza al paziente a causa della carenza di farmaci sono stati ritardi, trattamenti non ottimali e persino la completa cancellazione delle cure.<sup>3 <\/sup>Gli operatori sanitari hanno anche elencato l&#8217;aumento della durata della degenza e gli eventi avversi per la sicurezza, come l&#8217;errore di medicazione, il fallimento del trattamento e persino il decesso.<sup>3<\/sup><\/p>\n<p>Quando si verifica una carenza di farmaci, il 58% dei farmacisti, il 59% dei medici e il 50% degli infermieri non dispongono di un piano di emergenza per le sostituzioni terapeutiche.<sup>3<\/sup><\/p>\n<p>Tuttavia, la maggior parte degli operatori sanitari coinvolti nell\u2019indagine ha dovuto implementare cambiamenti clinici per gestire queste carenze, come il passaggio a un medicinale alternativo che potrebbe non essere altrettanto efficace, la conversione dalla forma endovenosa a quella orale di un medicinale e la modifica dei protocolli di somministrazione.<sup>3<\/sup><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Paesi di tutto il mondo si trovano ad affrontare un&#8217;ampia gamma di sfide nell&#8217;accesso ai prodotti sanitari necessari, come&#8230;<\/p>\n","protected":false},"author":8,"featured_media":7495,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[805],"tags":[],"class_list":["post-7492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pubblicazioni-scientifiche","speciality-economia-sanitaria","speciality-preparazione-farmaci","speciality-sicurezza-dei-pazienti","speciality-terapia-intensiva-cure-di-emergenza","contenttype-pubblicazioni","target-approvvigionamento","target-assistenza-infermieristica","target-direttore-manager-dellospedale","target-farmacia-clinica-it","target-medico","target-paziente"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La carenza di dispositivi e farmaci in Europa persiste - BD IV News<\/title>\n<meta name=\"description\" content=\"La nuova indagine dell&#039;EAHP descrive nel dettaglio la gravit\u00e0 e l\u2019impatto della carenza di dispositivi e farmaci in Europa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eu.bd.com\/iv-news\/it\/pubblicazioni-scientifiche\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La carenza di dispositivi e farmaci in Europa persiste - BD IV News\" \/>\n<meta property=\"og:description\" content=\"La nuova indagine dell&#039;EAHP descrive nel dettaglio la gravit\u00e0 e l\u2019impatto della carenza di dispositivi e farmaci in Europa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eu.bd.com\/iv-news\/it\/pubblicazioni-scientifiche\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\/\" \/>\n<meta property=\"og:site_name\" content=\"BD IV News\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-15T08:40:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2024\/03\/Drug_shortages_can_be_a_headache.png\" \/>\n\t<meta property=\"og:image:width\" content=\"994\" \/>\n\t<meta property=\"og:image:height\" content=\"423\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Camille Suarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camille Suarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/pubblicazioni-scientifiche\\\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/pubblicazioni-scientifiche\\\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\\\/\"},\"author\":{\"name\":\"Camille Suarez\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/person\\\/133274b3c3f2b1e2a25492760340ccf2\"},\"headline\":\"La carenza di dispositivi e farmaci in Europa persiste\",\"datePublished\":\"2024-04-15T08:40:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/pubblicazioni-scientifiche\\\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\\\/\"},\"wordCount\":646,\"publisher\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/pubblicazioni-scientifiche\\\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Drug_shortages_can_be_a_headache.png\",\"articleSection\":[\"Pubblicazioni scientifiche\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/pubblicazioni-scientifiche\\\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\\\/\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/pubblicazioni-scientifiche\\\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\\\/\",\"name\":\"La carenza di dispositivi e farmaci in Europa persiste - BD IV News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/pubblicazioni-scientifiche\\\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/pubblicazioni-scientifiche\\\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Drug_shortages_can_be_a_headache.png\",\"datePublished\":\"2024-04-15T08:40:04+00:00\",\"description\":\"La nuova indagine dell'EAHP descrive nel dettaglio la gravit\u00e0 e l\u2019impatto della carenza di dispositivi e farmaci in Europa.\",\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/pubblicazioni-scientifiche\\\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/pubblicazioni-scientifiche\\\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Drug_shortages_can_be_a_headache.png\",\"contentUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Drug_shortages_can_be_a_headache.png\",\"width\":994,\"height\":423,\"caption\":\"Report relativi alle indagini sulla carenza di dispositivi e farmaci in Europa.\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#website\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/\",\"name\":\"BD IV News\",\"description\":\"Your source of information on intravenous therapy, medication delivery and vascular access management.\",\"publisher\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#organization\",\"name\":\"BD IV News\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/BD-Master-Logo-on-Warm-White-512X512px.png\",\"contentUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/BD-Master-Logo-on-Warm-White-512X512px.png\",\"width\":512,\"height\":512,\"caption\":\"BD IV News\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/person\\\/133274b3c3f2b1e2a25492760340ccf2\",\"name\":\"Camille Suarez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g\",\"caption\":\"Camille Suarez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La carenza di dispositivi e farmaci in Europa persiste - BD IV News","description":"La nuova indagine dell'EAHP descrive nel dettaglio la gravit\u00e0 e l\u2019impatto della carenza di dispositivi e farmaci in Europa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eu.bd.com\/iv-news\/it\/pubblicazioni-scientifiche\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\/","og_locale":"en_GB","og_type":"article","og_title":"La carenza di dispositivi e farmaci in Europa persiste - BD IV News","og_description":"La nuova indagine dell'EAHP descrive nel dettaglio la gravit\u00e0 e l\u2019impatto della carenza di dispositivi e farmaci in Europa.","og_url":"https:\/\/eu.bd.com\/iv-news\/it\/pubblicazioni-scientifiche\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\/","og_site_name":"BD IV News","article_published_time":"2024-04-15T08:40:04+00:00","og_image":[{"width":994,"height":423,"url":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2024\/03\/Drug_shortages_can_be_a_headache.png","type":"image\/png"}],"author":"Camille Suarez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Camille Suarez","Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eu.bd.com\/iv-news\/it\/pubblicazioni-scientifiche\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\/#article","isPartOf":{"@id":"https:\/\/eu.bd.com\/iv-news\/it\/pubblicazioni-scientifiche\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\/"},"author":{"name":"Camille Suarez","@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/person\/133274b3c3f2b1e2a25492760340ccf2"},"headline":"La carenza di dispositivi e farmaci in Europa persiste","datePublished":"2024-04-15T08:40:04+00:00","mainEntityOfPage":{"@id":"https:\/\/eu.bd.com\/iv-news\/it\/pubblicazioni-scientifiche\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\/"},"wordCount":646,"publisher":{"@id":"https:\/\/eu.bd.com\/iv-news\/#organization"},"image":{"@id":"https:\/\/eu.bd.com\/iv-news\/it\/pubblicazioni-scientifiche\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2024\/03\/Drug_shortages_can_be_a_headache.png","articleSection":["Pubblicazioni scientifiche"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/eu.bd.com\/iv-news\/it\/pubblicazioni-scientifiche\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\/","url":"https:\/\/eu.bd.com\/iv-news\/it\/pubblicazioni-scientifiche\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\/","name":"La carenza di dispositivi e farmaci in Europa persiste - BD IV News","isPartOf":{"@id":"https:\/\/eu.bd.com\/iv-news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eu.bd.com\/iv-news\/it\/pubblicazioni-scientifiche\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\/#primaryimage"},"image":{"@id":"https:\/\/eu.bd.com\/iv-news\/it\/pubblicazioni-scientifiche\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2024\/03\/Drug_shortages_can_be_a_headache.png","datePublished":"2024-04-15T08:40:04+00:00","description":"La nuova indagine dell'EAHP descrive nel dettaglio la gravit\u00e0 e l\u2019impatto della carenza di dispositivi e farmaci in Europa.","inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eu.bd.com\/iv-news\/it\/pubblicazioni-scientifiche\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/eu.bd.com\/iv-news\/it\/pubblicazioni-scientifiche\/la-carenza-di-dispositivi-e-farmaci-in-europa-persiste\/#primaryimage","url":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2024\/03\/Drug_shortages_can_be_a_headache.png","contentUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2024\/03\/Drug_shortages_can_be_a_headache.png","width":994,"height":423,"caption":"Report relativi alle indagini sulla carenza di dispositivi e farmaci in Europa."},{"@type":"WebSite","@id":"https:\/\/eu.bd.com\/iv-news\/#website","url":"https:\/\/eu.bd.com\/iv-news\/","name":"BD IV News","description":"Your source of information on intravenous therapy, medication delivery and vascular access management.","publisher":{"@id":"https:\/\/eu.bd.com\/iv-news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eu.bd.com\/iv-news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/eu.bd.com\/iv-news\/#organization","name":"BD IV News","url":"https:\/\/eu.bd.com\/iv-news\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/logo\/image\/","url":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2024\/04\/BD-Master-Logo-on-Warm-White-512X512px.png","contentUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2024\/04\/BD-Master-Logo-on-Warm-White-512X512px.png","width":512,"height":512,"caption":"BD IV News"},"image":{"@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/person\/133274b3c3f2b1e2a25492760340ccf2","name":"Camille Suarez","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g","caption":"Camille Suarez"}}]}},"lang":"it","translations":{"it":7492,"en":7450,"de":7567,"es":7583,"fr":7604},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts\/7492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/comments?post=7492"}],"version-history":[{"count":3,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts\/7492\/revisions"}],"predecessor-version":[{"id":7496,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts\/7492\/revisions\/7496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/media\/7495"}],"wp:attachment":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/media?parent=7492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/categories?post=7492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/tags?post=7492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}