{"id":5805,"date":"2023-10-04T15:57:57","date_gmt":"2023-10-04T13:57:57","guid":{"rendered":"https:\/\/eu.bd.com\/iv-news\/?p=5805"},"modified":"2025-06-04T14:57:35","modified_gmt":"2025-06-04T12:57:35","slug":"wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert","status":"publish","type":"post","link":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\/","title":{"rendered":"Wie man das Risiko einer katheterassoziierten Thrombose erkennt und verringert"},"content":{"rendered":"<p>Katheterassoziierte Thrombosen geh\u00f6ren zu den h\u00e4ufigsten Komplikationen nach dem Anlegen eines zentralen Venenzugangs.<sup>1<\/sup><\/p>\n<p>Obwohl die Thematik bereits eingehend untersucht und diskutiert wurde, herrscht noch immer Unklarheit \u00fcber die verf\u00fcgbare Technik \/ die verf\u00fcgbaren Produkte, Punktionstechniken und Produktb\u00fcndeln.<sup>1,2<\/sup><\/p>\n<p>Dr. Fulvio Pinelli, Leiter des Zentrums f\u00fcr Gef\u00e4\u00dfzugang am Careggi-Universit\u00e4tskrankenhaus in Florenz, Italien, hielt einen Vortrag zu diesem Thema auf dem BD MACOVA-Kongress 2022 (Multidisciplinary Advanced Course on Vascular Access).<sup>2<\/sup><\/p>\n<h2>Katheterassoziierte Thrombose, Okklusion oder fibroblastische H\u00fcllen?<\/h2>\n<p>\u201eWenn wir \u00fcber Thrombose sprechen\u201c, sagte Dr. Pinelli, \u201em\u00fcssen wir uns \u00fcber die Definition im Klaren sein.\u201c<sup>2<\/sup><\/p>\n<p>Er wies darauf hin, dass ein Gro\u00dfteil der ver\u00f6ffentlichten Literatur die Unterschiede zwischen katheterassoziierter Thrombose, Okklusion und fibroblastischen H\u00fcllen noch immer nicht klar zu erkennen scheint.<sup>2<\/sup><\/p>\n<p>Dr. Pinelli bezeichnete die Okklusion als einen Zustand des inneren Katheterlumens, der durch ein intraluminales Gerinnsel verursacht wird.<sup>2<\/sup><\/p>\n<p>In den letzten 50 Jahren haben fibroblastische Ablagerungen verschiedene Namen erhalten, darunter Fibrinh\u00fcllen, Fibrinscheiden, Katheterablagerungen oder katheterassoziierte H\u00fcllen.<sup>2<\/sup><\/p>\n<p>W\u00e4hrend die Bezeichnungen \u201eH\u00fcllen\u201c und \u201eScheide\u201c korrekt sein m\u00f6gen, so Dr. Pinelli, sei \u201eFibrin\u201c sicher nicht korrekt, da eine fibroblastische H\u00fclle aus Bindegewebe besteht, dessen wichtigste nichtzellul\u00e4re Komponente Kollagen und nicht Fibrin ist.<sup>2<\/sup><\/p>\n<p>Als Fremdk\u00f6rperreaktion sind fibroblastische H\u00fcllen harmlos und erfordern in der Regel keine Behandlung.<sup>2<\/sup><\/p>\n<p>Dr. Pinelli stellte die drei Hauptfaktoren vor, die eine Thrombose bestimmen und wie sie sich von anderen Erkrankungen unterscheidet, ein System, das von dem Berliner Pathologen Rudolf Virchow gepr\u00e4gt wurde und als \u201eVirchow-Trias\u201c bekannt ist:<sup>2<\/sup><\/p>\n<ol>\n<li><strong>Endothelsch\u00e4den: <\/strong>Punktion<\/li>\n<li><strong>Blutstau:<\/strong> Vorhandensein des Katheters an sich, Infusionsfl\u00fcssigkeiten, Immobilisierung<\/li>\n<li><strong>Hyperkoagulabilit\u00e4t:<\/strong> Sepsis, b\u00f6sartige Erkrankungen, Entz\u00fcndungen, Thrombophilie<\/li>\n<\/ol>\n<p>\u201eWir k\u00f6nnen nicht viel gegen die Hyperkoagulabilit\u00e4t tun, sie ist ein Zustand des Patienten\u201c, sagte Dr. Pinelli. \u201eAber wir k\u00f6nnen etwas, wenn auch nicht alles, gegen Endothelsch\u00e4den und Blutstau tun.\u201c<sup>2<\/sup><\/p>\n<p><strong>Mehr zu diesem Thema: <\/strong><a href=\"https:\/\/eu.bd.com\/iv-news\/de\/ivlexikon\/\">Thrombose<\/a><\/p>\n\t\t\t\t\t<div class=\"gated_content\" id=\"gated_content-64ecbb140ee8e\">\n\t\t\t\t\t\t<div class=\"labelform notice-box margin-full\">\n\t\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-exclamation-triangle\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\tWerde VAMbassador, um Zugriff auf den vollst\u00e4ndigen Artikel zu erhalten\t\t\t\t\t\t\t<\/p>\n\n\t\t\t\t\t\t\t<div class=\"loginwrapper\">\n\t\t\t\t\t\t\t\t<form name=\"loginform\" id=\"loginform\" method=\"post\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"login-username\">\n\t\t\t\t\t\t\t\t\t\t<label for=\"user_login\"><\/label>\n\t\t\t\t\t\t\t\t\t\t<input required type=\"email\" name=\"log\" placeholder=\"Email address\" id=\"user_login\" class=\"input\" size=\"20\">\n\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<p class=\"login-password\">\n\t\t\t\t\t\t\t\t\t\t<label for=\"user_pass\"><\/label>\n\t\t\t\t\t\t\t\t\t\t<input required type=\"password\" name=\"pwd\" placeholder=\"Password\" id=\"user_pass\" class=\"input\" size=\"20\">\n\t\t\t\t\t\t\t\t\t\t<i class='fa fa-eye showpwd'><\/i>\n\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<p class=\"login-submit\">\n\t\t\t\t\t\t\t\t\t\t<input type=\"submit\" name=\"wp-submit\" id=\"wp-submit\" class=\"button button-primary\" value=\"Login\">\n\t\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"redirect_to\" value=\"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\/#gated_content-64ecbb140ee8e\">\n\t\t\t\t\t\t\t\t\t<\/p>\n\n\t\t\t\t\t\t\t\t\t<div class=\"aa_error hide\">\n\t\t\t\t\t\t\t\t\t\t<p><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<\/form>\n\n\t\t\t\t\t\t\t\t<div class='extralink'>\n\t\t\t\t\t\t\t\t\t<a class=\"forgot\" href=\"https:\/\/eu.bd.com\/iv-news\/it\/password-persa\/\">\n\t\t\t\t\t\t\t\t\t\tForgot your password?\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<br \/>\n\t\t\t\t\t\t\t\t\t<a class=\"register\" href=\"https:\/\/eu.bd.com\/iv-news\/fr\/inscription\/\">\n\t\t\t\t\t\t\t\t\t\tNot registered yet? <strong> Sign up <\/strong>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"content\" style=\"display:none;\">\n\t\t\t\t\t\t\t<p><iframe title=\"Thrombosis \u2013 causative factors and preventative measures at BD MACOVA 2022\" width=\"640\" height=\"360\" data-src=\"https:\/\/www.youtube.com\/embed\/H8_Oc9cTbSc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n<h2>Risikofaktoren f\u00fcr katheterassoziierte Thrombose<\/h2>\n<p>In einem Leitartikel aus dem Jahr 2021 untersuchte Dr. Pinelli die Konsensus-Publikation der italienischen Studiengruppe f\u00fcr langfristige zentrale Venenzug\u00e4nge (GAVeCeLT) aus dem Jahr 2007, um die Risikofaktoren f\u00fcr katheterassoziierte Thrombosen besser zu verstehen.<sup>1,2<\/sup><\/p>\n<h3>Er nannte die wichtigsten Risikobereiche:<sup>2<\/sup><\/h3>\n<ul>\n<li><strong>Wahl des Produkts: <\/strong>Typ, Material<\/li>\n<li><strong>Pr\u00e4disponierende Faktoren des Patienten<\/strong><\/li>\n<li><strong>Punktionstechnik:<\/strong> Verh\u00e4ltnis Katheter\/Vene, Ausma\u00df der Verletzung der Venenwand, Position der Spitze<\/li>\n<\/ul>\n<p>Dr. Pinelli kl\u00e4rte einige weit verbreitete Missverst\u00e4ndnisse im Zusammenhang mit der Wahl des Produkts auf, z. B. ob peripher eingef\u00fchrte Zentralvenenkatheter (PICC) anf\u00e4lliger f\u00fcr katheterassoziierte Thrombosen sind und ob die Wahl eines beschichteten oder mit einer bestimmten Substanz behandelten Produkts das Thromboserisiko verringert.<sup>2<\/sup><\/p>\n<p>Tats\u00e4chlich kam Dr. Pinelli zu dem Schluss, dass PICCs trotz bestimmter Studien eine sehr sichere Option sind und dass die vorhandenen Studien keine Belege daf\u00fcr liefern, dass beschichtete oder behandelte Produkte zur Verringerung des Thromboserisikos f\u00fchren.<sup>2<\/sup><\/p>\n<p>Dr. Pinelli stellte drei Studien \u00fcber die Verwendung beschichteter oder mit der Endexo-Technologie und mit Chlorhexidin-Gluconat (CHG) behandelter PICCs vor, was beides keinen Einfluss auf das Risiko katheterassoziierter Thrombosen hatte.<sup>2<\/sup><\/p>\n<p><strong>Mehr zu diesem Thema: <\/strong><a href=\"https:\/\/eu.bd.com\/iv-news\/news-innovation\/what-is-the-real-cost-of-vascular-access-related-complications\/\">Wie hoch sind die tats\u00e4chlichen Kosten bei Komplikationen im Zusammenhang mit Gef\u00e4\u00dfzugangssystemen?<\/a><\/p>\n<h2>Leitlinien f\u00fcr die Behandlung katheterassoziierter Thrombosen<\/h2>\n<p>\u201eDie beste Vorbeugung ist die richtige Technik beim Einf\u00fchren\u201c, so Dr. Pinelli.<sup>2<\/sup> Um das Trauma zu minimieren und Komplikationen zu vermeiden, hat er seine besten Tipps f\u00fcr das Einf\u00fchren aufgelistet:<sup>2<\/sup><\/p>\n<ul>\n<li><strong>Angemessene Wahl der Vene: <\/strong>W\u00e4hlen Sie die einfachste und sicherste Vene<\/li>\n<li><strong>Minimieren Sie das Venentrauma: <\/strong>Einsatz von Ultraschall wird dringend empfohlen<\/li>\n<li><strong>Beurteilen Sie die richtige Position der Spitze: <\/strong>Methode der Wahl bleibt die intrakavit\u00e4re Elektrokardiographie (IC EKG)<\/li>\n<li><strong>Stabilisieren Sie den Katheter: <\/strong>Anwendung einer multimodalen Strategie, einschlie\u00dflich der Wahl der richtigen Punktionsstelle und der Vorbereitung der Punktionsstelle<\/li>\n<\/ul>\n<p>Um die Einhaltung dieser Leitlinien zu gew\u00e4hrleisten, wies Dr. Pinelli darauf hin, dass die Verwendung von Katheter-Thrombose-B\u00fcndeln wie dem GAVeCeLT-B\u00fcndel (Gli Accessi Venosi Centrali a Lungo Termine) eine L\u00f6sung f\u00fcr eine korrekte Punktionstechnik sein k\u00f6nnten.<sup>2<\/sup><\/p>\n<h2>\u00dcber BD MACOVA 2022<\/h2>\n<p>Der BD MACOVA-Kongress\u00a02022 fand vom 8. bis 10.\u00a0Juni in Berlin statt und empfing \u00fcber 300\u00a0G\u00e4ste und 31\u00a0Redner aus 35\u00a0L\u00e4ndern.<\/p>\n<p>Die Veranstaltung hat eine lange Tradition. Dort teilen f\u00fchrende Experten im Bereich des Gef\u00e4\u00dfzugangs ihre Erfahrungen und Einblicke in das Gef\u00e4\u00dfzugangsmanagement (VAM, Vascular Access Management) mit denjenigen, die den Einsatz von Gef\u00e4\u00dfzugangssystemen und die Dienstleistungen in ihren Krankenh\u00e4usern erweitern m\u00f6chten.<\/p>\n<p>Das Thema war die Schaffung einer Gemeinschaft von \u201eVAM-Bassadors\u201c (Botschafter f\u00fcr Gef\u00e4\u00dfzugangsmanagement), die zur Verbesserung der Patientenergebnisse beitragen sollen.<\/p>\n<p><strong>Mehr zu diesem Thema: <\/strong><a href=\"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/picc-port-oder-hickman-treffen-sie-die-richtige-wahl-in-sachen-onkologie\/\">PICC, Port oder Hickman? Treffen Sie die richtige Wahl in Sachen Onkologie<\/a><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\n","protected":false},"excerpt":{"rendered":"<p>Katheterassoziierte Thrombosen geh\u00f6ren zu den h\u00e4ufigsten Komplikationen nach dem Anlegen eines zentralen Venenzugangs.1 Obwohl die Thematik bereits eingehend untersucht und&#8230;<\/p>\n","protected":false},"author":8,"featured_media":5553,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5620,533],"tags":[],"class_list":["post-5805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gated-content","category-veranstaltungen-schulung","speciality-intensivpflege-notfallversorgung","speciality-patientensicherheit","speciality-vaskulaerer-zugang","contenttype-artikel","target-arzt","target-krankenpflege"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wie man das Risiko einer katheterassoziierten Thrombose erkennt und verringert - BD IV News<\/title>\n<meta name=\"description\" content=\"Dr. Pinelli gibt Einblicke in die Erkennung katheterassoziierter Thrombosen und stellt die Leitlinien f\u00fcr bew\u00e4hrte Behandlungsmethoden vor.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie man das Risiko einer katheterassoziierten Thrombose erkennt und verringert - BD IV News\" \/>\n<meta property=\"og:description\" content=\"Dr. Pinelli gibt Einblicke in die Erkennung katheterassoziierter Thrombosen und stellt die Leitlinien f\u00fcr bew\u00e4hrte Behandlungsmethoden vor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\/\" \/>\n<meta property=\"og:site_name\" content=\"BD IV News\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-04T13:57:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-04T12:57:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2023\/08\/562A6890-resized.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1222\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Camille Suarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camille Suarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/de\\\/veranstaltungen-schulung\\\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/de\\\/veranstaltungen-schulung\\\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\\\/\"},\"author\":{\"name\":\"Camille Suarez\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/person\\\/133274b3c3f2b1e2a25492760340ccf2\"},\"headline\":\"Wie man das Risiko einer katheterassoziierten Thrombose erkennt und verringert\",\"datePublished\":\"2023-10-04T13:57:57+00:00\",\"dateModified\":\"2025-06-04T12:57:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/de\\\/veranstaltungen-schulung\\\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\\\/\"},\"wordCount\":329,\"publisher\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/de\\\/veranstaltungen-schulung\\\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/562A6890-resized.jpg\",\"articleSection\":[\"Gated Content\",\"Veranstaltungen und Schulung\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/de\\\/veranstaltungen-schulung\\\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\\\/\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/de\\\/veranstaltungen-schulung\\\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\\\/\",\"name\":\"Wie man das Risiko einer katheterassoziierten Thrombose erkennt und verringert - BD IV News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/de\\\/veranstaltungen-schulung\\\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/de\\\/veranstaltungen-schulung\\\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/562A6890-resized.jpg\",\"datePublished\":\"2023-10-04T13:57:57+00:00\",\"dateModified\":\"2025-06-04T12:57:35+00:00\",\"description\":\"Dr. Pinelli gibt Einblicke in die Erkennung katheterassoziierter Thrombosen und stellt die Leitlinien f\u00fcr bew\u00e4hrte Behandlungsmethoden vor.\",\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/de\\\/veranstaltungen-schulung\\\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/de\\\/veranstaltungen-schulung\\\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/562A6890-resized.jpg\",\"contentUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/562A6890-resized.jpg\",\"width\":1222,\"height\":520,\"caption\":\"El Dr. Fulvio Pinelli habla de las pautas de tratamiento de la trombosis asociada a cat\u00e9ter en BD MACOVA 2022\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#website\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/\",\"name\":\"BD IV News\",\"description\":\"Your source of information on intravenous therapy, medication delivery and vascular access management.\",\"publisher\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#organization\",\"name\":\"BD IV News\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/BD-Master-Logo-on-Warm-White-512X512px.png\",\"contentUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/BD-Master-Logo-on-Warm-White-512X512px.png\",\"width\":512,\"height\":512,\"caption\":\"BD IV News\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/person\\\/133274b3c3f2b1e2a25492760340ccf2\",\"name\":\"Camille Suarez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g\",\"caption\":\"Camille Suarez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie man das Risiko einer katheterassoziierten Thrombose erkennt und verringert - BD IV News","description":"Dr. Pinelli gibt Einblicke in die Erkennung katheterassoziierter Thrombosen und stellt die Leitlinien f\u00fcr bew\u00e4hrte Behandlungsmethoden vor.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\/","og_locale":"en_GB","og_type":"article","og_title":"Wie man das Risiko einer katheterassoziierten Thrombose erkennt und verringert - BD IV News","og_description":"Dr. Pinelli gibt Einblicke in die Erkennung katheterassoziierter Thrombosen und stellt die Leitlinien f\u00fcr bew\u00e4hrte Behandlungsmethoden vor.","og_url":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\/","og_site_name":"BD IV News","article_published_time":"2023-10-04T13:57:57+00:00","article_modified_time":"2025-06-04T12:57:35+00:00","og_image":[{"width":1222,"height":520,"url":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2023\/08\/562A6890-resized.jpg","type":"image\/jpeg"}],"author":"Camille Suarez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Camille Suarez","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\/#article","isPartOf":{"@id":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\/"},"author":{"name":"Camille Suarez","@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/person\/133274b3c3f2b1e2a25492760340ccf2"},"headline":"Wie man das Risiko einer katheterassoziierten Thrombose erkennt und verringert","datePublished":"2023-10-04T13:57:57+00:00","dateModified":"2025-06-04T12:57:35+00:00","mainEntityOfPage":{"@id":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\/"},"wordCount":329,"publisher":{"@id":"https:\/\/eu.bd.com\/iv-news\/#organization"},"image":{"@id":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2023\/08\/562A6890-resized.jpg","articleSection":["Gated Content","Veranstaltungen und Schulung"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\/","url":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\/","name":"Wie man das Risiko einer katheterassoziierten Thrombose erkennt und verringert - BD IV News","isPartOf":{"@id":"https:\/\/eu.bd.com\/iv-news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\/#primaryimage"},"image":{"@id":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2023\/08\/562A6890-resized.jpg","datePublished":"2023-10-04T13:57:57+00:00","dateModified":"2025-06-04T12:57:35+00:00","description":"Dr. Pinelli gibt Einblicke in die Erkennung katheterassoziierter Thrombosen und stellt die Leitlinien f\u00fcr bew\u00e4hrte Behandlungsmethoden vor.","inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/eu.bd.com\/iv-news\/de\/veranstaltungen-schulung\/wie-man-das-risiko-einer-katheterassoziierten-thrombose-erkennt-und-verringert\/#primaryimage","url":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2023\/08\/562A6890-resized.jpg","contentUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2023\/08\/562A6890-resized.jpg","width":1222,"height":520,"caption":"El Dr. Fulvio Pinelli habla de las pautas de tratamiento de la trombosis asociada a cat\u00e9ter en BD MACOVA 2022"},{"@type":"WebSite","@id":"https:\/\/eu.bd.com\/iv-news\/#website","url":"https:\/\/eu.bd.com\/iv-news\/","name":"BD IV News","description":"Your source of information on intravenous therapy, medication delivery and vascular access management.","publisher":{"@id":"https:\/\/eu.bd.com\/iv-news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eu.bd.com\/iv-news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/eu.bd.com\/iv-news\/#organization","name":"BD IV News","url":"https:\/\/eu.bd.com\/iv-news\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/logo\/image\/","url":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2024\/04\/BD-Master-Logo-on-Warm-White-512X512px.png","contentUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2024\/04\/BD-Master-Logo-on-Warm-White-512X512px.png","width":512,"height":512,"caption":"BD IV News"},"image":{"@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/person\/133274b3c3f2b1e2a25492760340ccf2","name":"Camille Suarez","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g","caption":"Camille Suarez"}}]}},"lang":"de","translations":{"de":5805,"it":5697,"en":5550,"fr":5823,"es":6973},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts\/5805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/comments?post=5805"}],"version-history":[{"count":6,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts\/5805\/revisions"}],"predecessor-version":[{"id":8918,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts\/5805\/revisions\/8918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/media\/5553"}],"wp:attachment":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/media?parent=5805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/categories?post=5805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/tags?post=5805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}