{"id":5344,"date":"2023-05-20T10:00:26","date_gmt":"2023-05-20T10:00:26","guid":{"rendered":"https:\/\/eu.bd.com\/iv-news\/?p=5344"},"modified":"2025-06-04T15:08:15","modified_gmt":"2025-06-04T13:08:15","slug":"misura-unica-non-va-bene-per-tutti","status":"publish","type":"post","link":"https:\/\/eu.bd.com\/iv-news\/it\/eventi-e-formazione\/misura-unica-non-va-bene-per-tutti\/","title":{"rendered":"Sviluppo di un team di accesso vascolare: una misura unica non va bene per tutti"},"content":{"rendered":"<p>I vantaggi di un team di accesso vascolare non sono un segreto. Nel Regno Unito, la NIVAS (National Infusion and Vascular Access Society, Societ\u00e0 Nazionale per l&#8217;infusione e l&#8217;accesso vascolare) afferma di poter contribuire a ridurre i ritardi di trattamento, le spese, la durata della degenza, i tassi di infezione e complicanze, migliorando al contempo l&#8217;esperienza del paziente, l&#8217;efficienza, la qualit\u00e0 dell&#8217;assistenza e gli outcome clinici.<sup>1<\/sup><\/p>\n<p>Secondo il Prof. Baudolino Mussa, chirurgo di accesso vascolare e Professore di accesso vascolare presso l&#8217;Universit\u00e0 di Torino in Italia, le esigenze di accesso vascolare variano da Paese a Paese, persino da ospedale a ospedale. Pertanto, la struttura di un team di accesso vascolare deve essere adattata per ogni singola struttura.<sup>2<\/sup><sup>,<\/sup><sup>3<\/sup><\/p>\n<p>In occasione del Multidisciplinary Advanced Course on Vascular Access (MACOVA) BD 2022, il Professor Mussa ha presentato due sondaggi regionali che esaminano pi\u00f9 da vicino le sfide, i vantaggi e le esigenze dei team di accesso vascolare in Europa.<\/p>\n<p><strong>Differenze locali nello sviluppo dei team di accesso vascolare<\/strong><\/p>\n<p>Sulla base di un&#8217;indagine qualitativa condotta in sei Paesi Europei, il Prof. Baudolino Mussa e\u00a0i suoi colleghi hanno scoperto che le strutture e le funzioni dei team di accesso vascolare esistenti variavano notevolmente tra loro.<sup>3<\/sup><\/p>\n<p>Ad esempio, non tutti gli intervistati concordano sul fatto che un team di accesso vascolare sia un programma gestito da personale infermieristico, con alcuni infermieri coinvolti solo part\u2011time.<sup>3<\/sup><\/p>\n<p>Un secondo sondaggio condotto negli stessi sei Paesi ha rilevato diversificazioni pi\u00f9 interessanti. Alcuni Paesi sono risultati pi\u00f9 avanzati di altri nello sviluppo di team per l&#8217;accesso vascolare e l&#8217;implementazione di tale team dipende molto dalle dimensioni e\u00a0dal\u00a0tipo di istituzione.<sup>4<\/sup><\/p>\n<p>\u00ab\u00c8 impossibile creare uno schema classico valido per tutti i Paesi\u00bb, ha affermato il Prof.\u00a0Baudolino Mussa. Questo \u00e8 il motivo per cui, ha insistito, ogni Paese deve progettare un team di accesso vascolare adatto alle proprie esigenze.<sup>2<\/sup><\/p>\n<p><strong>Ulteriori informazioni sul sondaggio: <\/strong><a href=\"https:\/\/eu.bd.com\/iv-news\/scientific-publications\/the-state-of-vascular-access-teams-results-of-a-european-survey\/\"><strong>Lo stato dei team di accesso vascolare: risultati di un sondaggio europeo<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n\t\t\t\t\t<div class=\"gated_content\" id=\"gated_content-6425920f09cb6\">\n\t\t\t\t\t\t<div class=\"labelform notice-box margin-full\">\n\t\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-exclamation-triangle\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\tDiventa un VAMbassador per accedere all'articolo completo\t\t\t\t\t\t\t<\/p>\n\n\t\t\t\t\t\t\t<div class=\"loginwrapper\">\n\t\t\t\t\t\t\t\t<form name=\"loginform\" id=\"loginform\" method=\"post\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"login-username\">\n\t\t\t\t\t\t\t\t\t\t<label for=\"user_login\"><\/label>\n\t\t\t\t\t\t\t\t\t\t<input required type=\"email\" name=\"log\" placeholder=\"Email address\" id=\"user_login\" class=\"input\" size=\"20\">\n\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<p class=\"login-password\">\n\t\t\t\t\t\t\t\t\t\t<label for=\"user_pass\"><\/label>\n\t\t\t\t\t\t\t\t\t\t<input required type=\"password\" name=\"pwd\" placeholder=\"Password\" id=\"user_pass\" class=\"input\" size=\"20\">\n\t\t\t\t\t\t\t\t\t\t<i class='fa fa-eye showpwd'><\/i>\n\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<p class=\"login-submit\">\n\t\t\t\t\t\t\t\t\t\t<input type=\"submit\" name=\"wp-submit\" id=\"wp-submit\" class=\"button button-primary\" value=\"Login\">\n\t\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"redirect_to\" value=\"https:\/\/eu.bd.com\/iv-news\/it\/eventi-e-formazione\/misura-unica-non-va-bene-per-tutti\/#gated_content-6425920f09cb6\">\n\t\t\t\t\t\t\t\t\t<\/p>\n\n\t\t\t\t\t\t\t\t\t<div class=\"aa_error hide\">\n\t\t\t\t\t\t\t\t\t\t<p><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<\/form>\n\n\t\t\t\t\t\t\t\t<div class='extralink'>\n\t\t\t\t\t\t\t\t\t<a class=\"forgot\" href=\"https:\/\/eu.bd.com\/iv-news\/it\/password-persa\/\">\n\t\t\t\t\t\t\t\t\t\tForgot your password?\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<br \/>\n\t\t\t\t\t\t\t\t\t<a class=\"register\" href=\"https:\/\/eu.bd.com\/iv-news\/fr\/inscription\/\">\n\t\t\t\t\t\t\t\t\t\tNot registered yet? <strong> Sign up <\/strong>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"content\" style=\"display:none;\">\n\t\t\t\t\t\t\t<p><iframe title=\"Development of a vascular access team: One size does not fit all\" width=\"640\" height=\"360\" data-src=\"https:\/\/www.youtube.com\/embed\/YRhhCu3gQW0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n<p><strong>Ostacoli in comune nello sviluppo di un team di accesso vascolare<\/strong><\/p>\n<p>Sebbene la realt\u00e0 dei team di accesso vascolare differisca in tutta la regione, il Prof. Baudolino Mussa ha notato che tutti gli intervistati hanno affrontato, e continuano ad\u00a0affrontare, sfide simili:<sup>3<\/sup><\/p>\n<ul>\n<li><strong>Mancanza di investimenti: <\/strong>i limiti di budget istituzionali e le questioni relative ai\u00a0rimborsi nelle regioni\/Paesi pregiudicano gli investimenti del team di accesso vascolare<\/li>\n<li><strong>Mancanza di consapevolezza:<\/strong> mancanza di consapevolezza da parte degli operatori sanitari rispetto al dispositivo appropriato nonch\u00e9 delle complicanze dovute alla scelta del dispositivo sbagliato o al posizionamento errato<\/li>\n<li><strong>Formazione insufficiente: <\/strong>di medici e personale infermieristico nelle scuole mediche\/infermieristiche e insufficiente aggiornamento periodico del personale ospedaliero<\/li>\n<li><strong>Inerzia: <\/strong>la gestione degli accessi vascolari pu\u00f2 essere data per scontata per la sua ubiquit\u00e0. Non viene riconosciuta come disciplina e specializzazione. Tutti i team di accesso vascolare necessitano di protocolli e stratificazione delle procedure, la cui creazione \u00e8 molto impegnativa e richiede molto tempo<\/li>\n<li><strong>Mancanza di prove definitive: <\/strong>non esiste un solido database delle complicanze a\u00a0livello europeo. La gestione e la segnalazione dei dati sono problematiche e\u00a0l&#8217;integrazione delle best practice tra le parti interessate \u00e8 difficile.<\/li>\n<\/ul>\n<p><strong>Ulteriori informazioni sullo sviluppo del proprio team di accesso vascolare: <\/strong><a href=\"https:\/\/eu.bd.com\/iv-news\/events-training\/make-the-case-for-a-vascular-access-team-by-convincing-with-facts-2\/\"><strong>Sostenere la\u00a0necessit\u00e0 di un team di accesso vascolare convincendo con i fatti<\/strong><\/a><\/p>\n<p><strong>I team di accesso vascolare possono incrementare l&#8217;attivit\u00e0 degli accessi vascolari<\/strong><\/p>\n<p>Sebbene lo sviluppo di un team di accesso vascolare comporti delle sfide, il Prof. Baudolino Mussa ha insistito sui vantaggi che il team comporta.<\/p>\n<p>\u00abI team di accesso vascolare sono importanti per aumentare l&#8217;efficacia e il tasso di posizionamento dei dispositivi all&#8217;interno dell&#8217;ospedale\u00bb, ha affermato.<sup>2<\/sup><\/p>\n<p>Presso l&#8217;Ospedale di Torino, il Professor Mussa e i suoi colleghi hanno registrato una maggiore attivit\u00e0 di accesso vascolare in seguito all&#8217;implementazione di un team di accesso vascolare dedicato, passando da circa 300 posizionamenti di catetere venoso centrale (CVC) a oltre 2.000.<sup>2<\/sup><\/p>\n<p>\u00abPreservare le vene del paziente, ridurre i costi, migliorare la qualit\u00e0 della vita e prevenire trattamenti futuri&#8230; I team di accesso vascolare sono l&#8217;unica soluzione di piena efficacia\u00bb, ha\u00a0dichiarato il Prof. Baudolino Mussa nel suo messaggio conclusivo.<sup>2<\/sup><\/p>\n<p><strong>Ulteriori informazioni sui vantaggi dei team di accesso vascolare: <\/strong><a href=\"https:\/\/eu.bd.com\/iv-news\/scientific-publications\/nivas-white-paper-the-benefits-of-a-vascular-access-team\/\"><strong>White paper NIVAS: i\u00a0vantaggi di un team di accesso vascolare<\/strong><\/a><\/p>\n<p><strong>Informazioni sul BD MACOVA 2022<\/strong><\/p>\n<p>Il BD MACOVA 2022 si \u00e8 tenuto a Berlino dall&#8217;8 al 10 giugno e ha accolto oltre 300 ospiti e\u00a031\u00a0relatori provenienti da 35 Paesi.<\/p>\n<p>L&#8217;evento coinvolge notoriamente i leader nell&#8217;accesso vascolare (VA) e ha lo scopo di condividere la loro esperienza e conoscenza della gestione dell&#8217;accesso vascolare (VAM) con coloro che desiderano espandere l&#8217;uso dei dispositivi di accesso vascolare e dei servizi che forniscono nei rispettivi ospedali.<\/p>\n<p>Il tema di quest&#8217;anno \u00e8 stato dedicato alla creazione di una comunit\u00e0 VA di VAM-bassadors (Ambasciatori della gestione dell&#8217;accesso vascolare) per favorire il miglioramento degli outcome nei pazienti.<\/p>\n    <div id=\"newslettercta\">\n        <div class=\"tnp tnp-subscription-minimal newsregister\">\n            <form method=\"post\" id=\"newsletter_form\">\n                <input id=\"email_newsletter\" class=\"tnp-email\" type=\"email\" required placeholder=\"Email\">\n                <input id=\"submit_newsletter\" class=\"tnp-submit\" type=\"submit\" value=\"Subscribe\">\n\n                <label>\n                    <input type=\"checkbox\" name=\"accept\" required \/>\n                    <small>\n                        Send me the BD IV News newsletter. I expressly agree to receive the newsletter and know that I can easily unsubscribe at any time.                    <\/small>\n                <\/label>\n                <p id=\"validamessage\" style=\"display: none;color: #00b8b0;margin: 5px 0;\">\n\n                    Thank you for your registration.\n                <\/p>\n            <\/form>\n        <\/div>\n    <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I vantaggi di un team di accesso vascolare non sono un segreto. Nel Regno Unito, la NIVAS (National Infusion and&#8230;<\/p>\n","protected":false},"author":8,"featured_media":5256,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[801,5629],"tags":[],"class_list":["post-5344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi-e-formazione","category-gated-content","speciality-accesso-vascolare","contenttype-articolo","target-assistenza-infermieristica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sviluppo di un team di accesso vascolare: una misura unica non va bene per tutti - BD IV News<\/title>\n<meta name=\"description\" content=\"Al MACOVA 2022, il Prof. Baudolino Mussa ha presentato nuove scoperte sullo sviluppo di un team per gli accessi vascolari e sulle differenze a livello europeo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eu.bd.com\/iv-news\/it\/eventi-e-formazione\/misura-unica-non-va-bene-per-tutti\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sviluppo di un team di accesso vascolare: una misura unica non va bene per tutti - BD IV News\" \/>\n<meta property=\"og:description\" content=\"Al MACOVA 2022, il Prof. Baudolino Mussa ha presentato nuove scoperte sullo sviluppo di un team per gli accessi vascolari e sulle differenze a livello europeo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eu.bd.com\/iv-news\/it\/eventi-e-formazione\/misura-unica-non-va-bene-per-tutti\/\" \/>\n<meta property=\"og:site_name\" content=\"BD IV News\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-20T10:00:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-04T13:08:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2023\/03\/MACOVA-resized.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1222\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Camille Suarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camille Suarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/eventi-e-formazione\\\/misura-unica-non-va-bene-per-tutti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/eventi-e-formazione\\\/misura-unica-non-va-bene-per-tutti\\\/\"},\"author\":{\"name\":\"Camille Suarez\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/person\\\/133274b3c3f2b1e2a25492760340ccf2\"},\"headline\":\"Sviluppo di un team di accesso vascolare: una misura unica non va bene per tutti\",\"datePublished\":\"2023-05-20T10:00:26+00:00\",\"dateModified\":\"2025-06-04T13:08:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/eventi-e-formazione\\\/misura-unica-non-va-bene-per-tutti\\\/\"},\"wordCount\":354,\"publisher\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/eventi-e-formazione\\\/misura-unica-non-va-bene-per-tutti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/MACOVA-resized.png\",\"articleSection\":[\"Eventi e formazione\",\"Gated Content\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/eventi-e-formazione\\\/misura-unica-non-va-bene-per-tutti\\\/\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/eventi-e-formazione\\\/misura-unica-non-va-bene-per-tutti\\\/\",\"name\":\"Sviluppo di un team di accesso vascolare: una misura unica non va bene per tutti - BD IV News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/eventi-e-formazione\\\/misura-unica-non-va-bene-per-tutti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/eventi-e-formazione\\\/misura-unica-non-va-bene-per-tutti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/MACOVA-resized.png\",\"datePublished\":\"2023-05-20T10:00:26+00:00\",\"dateModified\":\"2025-06-04T13:08:15+00:00\",\"description\":\"Al MACOVA 2022, il Prof. Baudolino Mussa ha presentato nuove scoperte sullo sviluppo di un team per gli accessi vascolari e sulle differenze a livello europeo.\",\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/eventi-e-formazione\\\/misura-unica-non-va-bene-per-tutti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/eventi-e-formazione\\\/misura-unica-non-va-bene-per-tutti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/MACOVA-resized.png\",\"contentUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/MACOVA-resized.png\",\"width\":1222,\"height\":520,\"caption\":\"Professor Mussa discusses the development of a vascular access team at MACOVA 2022.\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#website\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/\",\"name\":\"BD IV News\",\"description\":\"Your source of information on intravenous therapy, medication delivery and vascular access management.\",\"publisher\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#organization\",\"name\":\"BD IV News\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/BD-Master-Logo-on-Warm-White-512X512px.png\",\"contentUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/BD-Master-Logo-on-Warm-White-512X512px.png\",\"width\":512,\"height\":512,\"caption\":\"BD IV News\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/person\\\/133274b3c3f2b1e2a25492760340ccf2\",\"name\":\"Camille Suarez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g\",\"caption\":\"Camille Suarez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sviluppo di un team di accesso vascolare: una misura unica non va bene per tutti - BD IV News","description":"Al MACOVA 2022, il Prof. Baudolino Mussa ha presentato nuove scoperte sullo sviluppo di un team per gli accessi vascolari e sulle differenze a livello europeo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eu.bd.com\/iv-news\/it\/eventi-e-formazione\/misura-unica-non-va-bene-per-tutti\/","og_locale":"en_GB","og_type":"article","og_title":"Sviluppo di un team di accesso vascolare: una misura unica non va bene per tutti - BD IV News","og_description":"Al MACOVA 2022, il Prof. Baudolino Mussa ha presentato nuove scoperte sullo sviluppo di un team per gli accessi vascolari e sulle differenze a livello europeo.","og_url":"https:\/\/eu.bd.com\/iv-news\/it\/eventi-e-formazione\/misura-unica-non-va-bene-per-tutti\/","og_site_name":"BD IV News","article_published_time":"2023-05-20T10:00:26+00:00","article_modified_time":"2025-06-04T13:08:15+00:00","og_image":[{"width":1222,"height":520,"url":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2023\/03\/MACOVA-resized.png","type":"image\/png"}],"author":"Camille Suarez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Camille Suarez","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eu.bd.com\/iv-news\/it\/eventi-e-formazione\/misura-unica-non-va-bene-per-tutti\/#article","isPartOf":{"@id":"https:\/\/eu.bd.com\/iv-news\/it\/eventi-e-formazione\/misura-unica-non-va-bene-per-tutti\/"},"author":{"name":"Camille Suarez","@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/person\/133274b3c3f2b1e2a25492760340ccf2"},"headline":"Sviluppo di un team di accesso vascolare: una misura unica non va bene per tutti","datePublished":"2023-05-20T10:00:26+00:00","dateModified":"2025-06-04T13:08:15+00:00","mainEntityOfPage":{"@id":"https:\/\/eu.bd.com\/iv-news\/it\/eventi-e-formazione\/misura-unica-non-va-bene-per-tutti\/"},"wordCount":354,"publisher":{"@id":"https:\/\/eu.bd.com\/iv-news\/#organization"},"image":{"@id":"https:\/\/eu.bd.com\/iv-news\/it\/eventi-e-formazione\/misura-unica-non-va-bene-per-tutti\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2023\/03\/MACOVA-resized.png","articleSection":["Eventi e formazione","Gated Content"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/eu.bd.com\/iv-news\/it\/eventi-e-formazione\/misura-unica-non-va-bene-per-tutti\/","url":"https:\/\/eu.bd.com\/iv-news\/it\/eventi-e-formazione\/misura-unica-non-va-bene-per-tutti\/","name":"Sviluppo di un team di accesso vascolare: una misura unica non va bene per tutti - BD IV News","isPartOf":{"@id":"https:\/\/eu.bd.com\/iv-news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eu.bd.com\/iv-news\/it\/eventi-e-formazione\/misura-unica-non-va-bene-per-tutti\/#primaryimage"},"image":{"@id":"https:\/\/eu.bd.com\/iv-news\/it\/eventi-e-formazione\/misura-unica-non-va-bene-per-tutti\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2023\/03\/MACOVA-resized.png","datePublished":"2023-05-20T10:00:26+00:00","dateModified":"2025-06-04T13:08:15+00:00","description":"Al MACOVA 2022, il Prof. Baudolino Mussa ha presentato nuove scoperte sullo sviluppo di un team per gli accessi vascolari e sulle differenze a livello europeo.","inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eu.bd.com\/iv-news\/it\/eventi-e-formazione\/misura-unica-non-va-bene-per-tutti\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/eu.bd.com\/iv-news\/it\/eventi-e-formazione\/misura-unica-non-va-bene-per-tutti\/#primaryimage","url":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2023\/03\/MACOVA-resized.png","contentUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2023\/03\/MACOVA-resized.png","width":1222,"height":520,"caption":"Professor Mussa discusses the development of a vascular access team at MACOVA 2022."},{"@type":"WebSite","@id":"https:\/\/eu.bd.com\/iv-news\/#website","url":"https:\/\/eu.bd.com\/iv-news\/","name":"BD IV News","description":"Your source of information on intravenous therapy, medication delivery and vascular access management.","publisher":{"@id":"https:\/\/eu.bd.com\/iv-news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eu.bd.com\/iv-news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/eu.bd.com\/iv-news\/#organization","name":"BD IV News","url":"https:\/\/eu.bd.com\/iv-news\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/logo\/image\/","url":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2024\/04\/BD-Master-Logo-on-Warm-White-512X512px.png","contentUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2024\/04\/BD-Master-Logo-on-Warm-White-512X512px.png","width":512,"height":512,"caption":"BD IV News"},"image":{"@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/person\/133274b3c3f2b1e2a25492760340ccf2","name":"Camille Suarez","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g","caption":"Camille Suarez"}}]}},"lang":"it","translations":{"it":5344,"en":5247},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts\/5344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/comments?post=5344"}],"version-history":[{"count":5,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts\/5344\/revisions"}],"predecessor-version":[{"id":8933,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts\/5344\/revisions\/8933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/media\/5256"}],"wp:attachment":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/media?parent=5344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/categories?post=5344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/tags?post=5344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}