{"id":4782,"date":"2022-10-10T00:00:45","date_gmt":"2022-10-10T00:00:45","guid":{"rendered":"https:\/\/eu.bd.com\/iv-news\/?p=4782"},"modified":"2022-09-30T07:57:32","modified_gmt":"2022-09-30T07:57:32","slug":"regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745","status":"publish","type":"post","link":"https:\/\/eu.bd.com\/iv-news\/it\/novita-e-innovazione\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\/","title":{"rendered":"Regolamento dell&#8217;Unione Europea sui dispositivi medici (MDR) 2017\/745"},"content":{"rendered":"<h4><strong>Introduzione\u00a0<\/strong><\/h4>\n<p>L&#8217;Unione Europea (UE) ha adottato l&#8217;MDR quasi 10 anni dopo aver avviato una revisione formale del quadro normativo europeo. L&#8217;MDR \u00e8 entrato in vigore il 26 maggio 2017 ed \u00e8 diventato applicabile in tutti gli Stati membri dell&#8217;UE il 26 maggio 2021. Questo nuovo regolamento ha sostituito la precedente Direttiva sui dispositivi medici (MDD)\u00a0e stabilisce nuove disposizioni per l&#8217;applicazione del marchio &#8220;CE&#8221; ai dispositivi medici (MD).<\/p>\n<h4><strong>\u00a0Che cosa porta con s\u00e9 l&#8217;MDR\u00a0<\/strong><\/h4>\n<p>Le nuove normative mirano ad apportare importanti miglioramenti all&#8217;attuale sistema. Le finalit\u00e0 delle nuove disposizioni sono<sup>1<\/sup>:<\/p>\n<ul>\n<li><strong>Controllo pre-commercializzazione pi\u00f9 severi per i dispositivi ad alto rischio<\/strong>, con il coinvolgimento di un pool di esperti a livello dell&#8217;UE<\/li>\n<li><strong>Criteri pi\u00f9 rigorosi per la designazione e le procedure di supervisione degli Organismi notificati<\/strong><\/li>\n<li><strong>Inclusione di alcuni dispositivi estetici e cosmetici <\/strong>(ad es.: lenti a contatto, impianti di collagene, apparecchiature per la rimozione dei tatuaggi, apparecchiature per la liposuzione e filler dermici) nell&#8217;ambito del regolamento.<\/li>\n<li><strong>Maggiore trasparenza <\/strong>tramite una banca dati completa dell&#8217;UE sui dispositivi medici e un sistema di tracciabilit\u00e0 dei dispositivi basato sull&#8217;identificazione univoca del dispositivo<\/li>\n<li><strong>Introduzione di una &#8220;tessera per il portatore di impianto&#8221; <\/strong>destinata ai pazienti, recante informazioni sui dispositivi medici impiantati<\/li>\n<li><strong>Rafforzamento delle norme sull&#8217;evidenza clinica<\/strong>, compresa una procedura coordinata a livello dell&#8217;UE per l&#8217;autorizzazione di indagini cliniche multicentriche<\/li>\n<li><strong>Rafforzamento dei requisiti di sorveglianza post-commercializzazione<\/strong> per i produttori<\/li>\n<li><strong>Miglioramento dei meccanismi di coordinamento <\/strong>tra i Paesi dell&#8217;UE nel campo della vigilanza e della sorveglianza del mercato<\/li>\n<\/ul>\n<h4><strong>Perch\u00e9 l&#8217;MDR \u00e8 importante\u00a0<\/strong><\/h4>\n<p>L&#8217;MDR dell&#8217;UE mira a garantire il buon funzionamento del mercato interno per i dispositivi medici, prendendo come base un livello elevato di protezione della salute dei pazienti e degli utenti. Nel contempo, il regolamento fissa standard elevati di qualit\u00e0 e sicurezza per i dispositivi medici, con la finalit\u00e0 di soddisfare i comuni problemi di sicurezza garantendo, tra\u00a0l&#8217;altro, l&#8217;affidabilit\u00e0 e la solidit\u00e0 dei dati generati nelle indagini cliniche e la tutela della sicurezza dei soggetti che partecipano a tali indagini.<\/p>\n<h4><strong>BD e MDR\u00a0<\/strong><\/h4>\n<p>In quanto leader nell&#8217;assistenza sanitaria e nella sicurezza dei pazienti, <a href=\"https:\/\/www.bd.com\/en-eu\/company\/mdr\/ivdr-update\">BD<\/a> promuove l&#8217;implementazione di politiche e procedure per garantire la conformit\u00e0 all&#8217;MDR. Stiamo attualmente conducendo un&#8217;attenta revisione del nostro portafoglio di prodotti per aumentare, ove possibile, l&#8217;efficienza. Noi di BD ci impegniamo a servire i nostri clienti fornendo dispositivi medici sicuri ed efficaci, conformi a tutte le normative vigenti.<\/p>\n<p><span class=\"TextRun SCXW21720692 BCX0\" lang=\"EN-US\" xml:lang=\"EN-US\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW21720692 BCX0\"><div class=\"su-button-center\"><a href=\"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2022\/09\/BD-73764-MDR-Regulation-Brochure-EuropeITALIAN-compressed.pdf\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#2D89EF;border-color:#246ec0;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:6px 16px;font-size:13px;line-height:20px;border-color:#6cadf4;border-radius:5px;text-shadow:none\"><i class=\"sui sui-search\" style=\"font-size:13px;color:#FFFFFF\"><\/i> Scarica la brochure MDR<\/span><\/a><\/div><\/span><\/span><span class=\"EOP SCXW21720692 BCX0\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n    <div id=\"newslettercta\">\n        <div class=\"tnp tnp-subscription-minimal newsregister\">\n            <form method=\"post\" id=\"newsletter_form\">\n                <input id=\"email_newsletter\" class=\"tnp-email\" type=\"email\" required placeholder=\"Email\">\n                <input id=\"submit_newsletter\" class=\"tnp-submit\" type=\"submit\" value=\"Subscribe\">\n\n                <label>\n                    <input type=\"checkbox\" name=\"accept\" required \/>\n                    <small>\n                        Send me the BD IV News newsletter. I expressly agree to receive the newsletter and know that I can easily unsubscribe at any time.                    <\/small>\n                <\/label>\n                <p id=\"validamessage\" style=\"display: none;color: #00b8b0;margin: 5px 0;\">\n\n                    Thank you for your registration.\n                <\/p>\n            <\/form>\n        <\/div>\n    <\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Introduzione\u00a0 L&#8217;Unione Europea (UE) ha adottato l&#8217;MDR quasi 10 anni dopo aver avviato una revisione formale del quadro normativo europeo&#8230;.<\/p>\n","protected":false},"author":8,"featured_media":4783,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[753],"tags":[],"class_list":["post-4782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novita-e-innovazione","speciality-sicurezza-dei-pazienti","contenttype-articolo","target-medico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Regolamento dell&#039;Unione Europea sui dispositivi medici (MDR) 2017\/745<\/title>\n<meta name=\"description\" content=\"Il regolamento europeo sui dispositivi medici (MDR) 2017\/745 contiene una serie di miglioramenti volti ad aggiornare la legislazione tenendo conto dei progressi della medicina.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eu.bd.com\/iv-news\/it\/novita-e-innovazione\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Regolamento dell&#039;Unione Europea sui dispositivi medici (MDR) 2017\/745\" \/>\n<meta property=\"og:description\" content=\"Il regolamento europeo sui dispositivi medici (MDR) 2017\/745 contiene una serie di miglioramenti volti ad aggiornare la legislazione tenendo conto dei progressi della medicina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eu.bd.com\/iv-news\/it\/novita-e-innovazione\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\/\" \/>\n<meta property=\"og:site_name\" content=\"BD IV News\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-10T00:00:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2022\/03\/MDR-Medical-article-2-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1222\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Camille Suarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camille Suarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/novita-e-innovazione\\\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/novita-e-innovazione\\\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\\\/\"},\"author\":{\"name\":\"Camille Suarez\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/person\\\/133274b3c3f2b1e2a25492760340ccf2\"},\"headline\":\"Regolamento dell&#8217;Unione Europea sui dispositivi medici (MDR) 2017\\\/745\",\"datePublished\":\"2022-10-10T00:00:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/novita-e-innovazione\\\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\\\/\"},\"wordCount\":440,\"publisher\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/novita-e-innovazione\\\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/MDR-Medical-article-2-1.png\",\"articleSection\":[\"Novit\u00e0 e innovazione\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/novita-e-innovazione\\\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\\\/\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/novita-e-innovazione\\\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\\\/\",\"name\":\"Regolamento dell'Unione Europea sui dispositivi medici (MDR) 2017\\\/745\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/novita-e-innovazione\\\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/novita-e-innovazione\\\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/MDR-Medical-article-2-1.png\",\"datePublished\":\"2022-10-10T00:00:45+00:00\",\"description\":\"Il regolamento europeo sui dispositivi medici (MDR) 2017\\\/745 contiene una serie di miglioramenti volti ad aggiornare la legislazione tenendo conto dei progressi della medicina.\",\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/novita-e-innovazione\\\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/it\\\/novita-e-innovazione\\\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/MDR-Medical-article-2-1.png\",\"contentUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/MDR-Medical-article-2-1.png\",\"width\":1222,\"height\":520,\"caption\":\"Un operatore sanitario che esamina un dispositivo medico, interessato dall'MDR\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#website\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/\",\"name\":\"BD IV News\",\"description\":\"Your source of information on intravenous therapy, medication delivery and vascular access management.\",\"publisher\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#organization\",\"name\":\"BD IV News\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/BD-Master-Logo-on-Warm-White-512X512px.png\",\"contentUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/BD-Master-Logo-on-Warm-White-512X512px.png\",\"width\":512,\"height\":512,\"caption\":\"BD IV News\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/person\\\/133274b3c3f2b1e2a25492760340ccf2\",\"name\":\"Camille Suarez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g\",\"caption\":\"Camille Suarez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Regolamento dell'Unione Europea sui dispositivi medici (MDR) 2017\/745","description":"Il regolamento europeo sui dispositivi medici (MDR) 2017\/745 contiene una serie di miglioramenti volti ad aggiornare la legislazione tenendo conto dei progressi della medicina.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eu.bd.com\/iv-news\/it\/novita-e-innovazione\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\/","og_locale":"en_GB","og_type":"article","og_title":"Regolamento dell'Unione Europea sui dispositivi medici (MDR) 2017\/745","og_description":"Il regolamento europeo sui dispositivi medici (MDR) 2017\/745 contiene una serie di miglioramenti volti ad aggiornare la legislazione tenendo conto dei progressi della medicina.","og_url":"https:\/\/eu.bd.com\/iv-news\/it\/novita-e-innovazione\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\/","og_site_name":"BD IV News","article_published_time":"2022-10-10T00:00:45+00:00","og_image":[{"width":1222,"height":520,"url":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2022\/03\/MDR-Medical-article-2-1.png","type":"image\/png"}],"author":"Camille Suarez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Camille Suarez","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eu.bd.com\/iv-news\/it\/novita-e-innovazione\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\/#article","isPartOf":{"@id":"https:\/\/eu.bd.com\/iv-news\/it\/novita-e-innovazione\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\/"},"author":{"name":"Camille Suarez","@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/person\/133274b3c3f2b1e2a25492760340ccf2"},"headline":"Regolamento dell&#8217;Unione Europea sui dispositivi medici (MDR) 2017\/745","datePublished":"2022-10-10T00:00:45+00:00","mainEntityOfPage":{"@id":"https:\/\/eu.bd.com\/iv-news\/it\/novita-e-innovazione\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\/"},"wordCount":440,"publisher":{"@id":"https:\/\/eu.bd.com\/iv-news\/#organization"},"image":{"@id":"https:\/\/eu.bd.com\/iv-news\/it\/novita-e-innovazione\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2022\/03\/MDR-Medical-article-2-1.png","articleSection":["Novit\u00e0 e innovazione"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/eu.bd.com\/iv-news\/it\/novita-e-innovazione\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\/","url":"https:\/\/eu.bd.com\/iv-news\/it\/novita-e-innovazione\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\/","name":"Regolamento dell'Unione Europea sui dispositivi medici (MDR) 2017\/745","isPartOf":{"@id":"https:\/\/eu.bd.com\/iv-news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eu.bd.com\/iv-news\/it\/novita-e-innovazione\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\/#primaryimage"},"image":{"@id":"https:\/\/eu.bd.com\/iv-news\/it\/novita-e-innovazione\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2022\/03\/MDR-Medical-article-2-1.png","datePublished":"2022-10-10T00:00:45+00:00","description":"Il regolamento europeo sui dispositivi medici (MDR) 2017\/745 contiene una serie di miglioramenti volti ad aggiornare la legislazione tenendo conto dei progressi della medicina.","inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eu.bd.com\/iv-news\/it\/novita-e-innovazione\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/eu.bd.com\/iv-news\/it\/novita-e-innovazione\/regolamento-dellunione-europea-sui-dispositivi-medici-mdr-2017-745\/#primaryimage","url":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2022\/03\/MDR-Medical-article-2-1.png","contentUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2022\/03\/MDR-Medical-article-2-1.png","width":1222,"height":520,"caption":"Un operatore sanitario che esamina un dispositivo medico, interessato dall'MDR"},{"@type":"WebSite","@id":"https:\/\/eu.bd.com\/iv-news\/#website","url":"https:\/\/eu.bd.com\/iv-news\/","name":"BD IV News","description":"Your source of information on intravenous therapy, medication delivery and vascular access management.","publisher":{"@id":"https:\/\/eu.bd.com\/iv-news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eu.bd.com\/iv-news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/eu.bd.com\/iv-news\/#organization","name":"BD IV News","url":"https:\/\/eu.bd.com\/iv-news\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/logo\/image\/","url":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2024\/04\/BD-Master-Logo-on-Warm-White-512X512px.png","contentUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2024\/04\/BD-Master-Logo-on-Warm-White-512X512px.png","width":512,"height":512,"caption":"BD IV News"},"image":{"@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/person\/133274b3c3f2b1e2a25492760340ccf2","name":"Camille Suarez","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g","caption":"Camille Suarez"}}]}},"lang":"it","translations":{"it":4782},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts\/4782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/comments?post=4782"}],"version-history":[{"count":3,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts\/4782\/revisions"}],"predecessor-version":[{"id":4786,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts\/4782\/revisions\/4786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/media\/4783"}],"wp:attachment":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/media?parent=4782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/categories?post=4782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/tags?post=4782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}