{"id":3707,"date":"2021-07-27T00:00:04","date_gmt":"2021-07-27T00:00:04","guid":{"rendered":"https:\/\/eu.bd.com\/iv-news\/?p=3707"},"modified":"2022-07-27T08:21:04","modified_gmt":"2022-07-27T08:21:04","slug":"como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones","status":"publish","type":"post","link":"https:\/\/eu.bd.com\/iv-news\/es\/novedades-e-innovacion\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\/","title":{"rendered":"C\u00f3mo las mejores pr\u00e1cticas en el acceso vascular pueden ayudar a fomentar una cultura de seguridad y prevenci\u00f3n de infecciones"},"content":{"rendered":"<p><em>Art\u00edculo publicado originalmente en diciembre de 2021. Publicado de nuevo como parte de nuestra serie de verano sobre los art\u00edculos m\u00e1s populares.<\/em><\/p>\n<p><em>Este es el segundo art\u00edculo de una serie de cuatro destinados a sacar a la luz las complicaciones del acceso vascular. El primero se puede consular <a href=\"https:\/\/eu.bd.com\/iv-news\/es\/novedades-e-innovacion\/el-coste-real-de-las-infecciones-del-torrente-sanguineo-relacionadas-con-el-cateter\/\">aqu\u00ed.<\/a><\/em><\/p>\n<p>Las complicaciones del acceso vascular son causa de numerosos problemas para los pacientes y los hospitales.<\/p>\n<p>\u00bfSab\u00eda que las infecciones del torrente sangu\u00edneo asociadas a los cat\u00e9teres (CRBSI, por sus siglas en ingl\u00e9s) son un problema cl\u00ednico importante que incide en un significativo incremento de morbilidad, mortalidad y coste econ\u00f3mico?<sup>1<\/sup><\/p>\n<p>Debido a que hasta el 90 % de los pacientes hospitalizados requieren tratamiento intravenoso perif\u00e9rico, muchos de ellos tienen un riesgo potencial de CRBSI.<sup>2<\/sup><\/p>\n<p>Adem\u00e1s de las CRBSI, una atenci\u00f3n inadecuada del acceso vascular tambi\u00e9n puede contribuir a muchas otras complicaciones, como flebitis, oclusi\u00f3n, desplazamiento, trombosis, infiltraci\u00f3n y extravasaci\u00f3n.<sup>2<\/sup><\/p>\n<p>Algunas complicaciones pueden producir dolor y molestias al paciente y pueden prolongar su estancia hospitalaria.<sup>2<\/sup> Otras son m\u00e1s graves y pueden resultar mortales.<sup>3<\/sup><\/p>\n<p>Al defender las mejores pr\u00e1cticas en la atenci\u00f3n del acceso vascular en su hospital, ayuda a fomentar una cultura de prevenci\u00f3n y seguridad del paciente.<\/p>\n<p>El impulso de las pr\u00e1cticas recomendadas basadas en la evidencia contribuye a:<\/p>\n<ul>\n<li>Concienciar acerca de las complicaciones por infecci\u00f3n.<\/li>\n<li>Estandarizar las pol\u00edticas y los procedimientos de supervisi\u00f3n.<\/li>\n<li>Supervisar las infecciones asociadas a un cat\u00e9ter y las complicaciones intravenosas en general.<\/li>\n<li>Garantizar la uniformidad de los procedimientos.<\/li>\n<li>Mejorar la calidad de la asistencia y la seguridad de los pacientes y, en \u00faltima instancia, la reputaci\u00f3n de su hospital.<\/li>\n<\/ul>\n<p>Para obtener m\u00e1s informaci\u00f3n sobre los beneficios de las mejores pr\u00e1cticas de acceso vascular para la prevenci\u00f3n de infecciones, haga clic en el enlace a continuaci\u00f3n:<\/p>\n<p class=\"p1\"><div class=\"su-button-center\"><a href=\"https:\/\/lp.bd.com\/202107-MDS21-EU_ES-VAM_complication_awareness-LP_LP-EN-01-Main-LP.html\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#2D89EF;border-color:#246ec0;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#6cadf4;border-radius:5px;text-shadow:none\"> M\u00e1s informaci\u00f3n<\/span><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Art\u00edculo publicado originalmente en diciembre de 2021. Publicado de nuevo como parte de nuestra serie de verano sobre los art\u00edculos&#8230;<\/p>\n","protected":false},"author":8,"featured_media":3708,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[369],"tags":[],"class_list":["post-3707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades-e-innovacion","speciality-acceso-vascular","speciality-anestesiologia","speciality-cuidados-intensivos-emergencias","speciality-prevencion-de-infecciones","speciality-seguridad-del-paciente","contenttype-articulo","target-doctor-a","target-enfermeria","target-prevencion-de-infecciones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo las mejores pr\u00e1cticas en el acceso vascular pueden ayudar a prevenir de infecciones<\/title>\n<meta name=\"description\" content=\"\u00bfSab\u00eda que las infecciones del torrente sangu\u00edneo asociadas a los cat\u00e9teres son un problema cl\u00ednico importante ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eu.bd.com\/iv-news\/es\/novedades-e-innovacion\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo las mejores pr\u00e1cticas en el acceso vascular pueden ayudar a prevenir de infecciones\" \/>\n<meta property=\"og:description\" content=\"\u00bfSab\u00eda que las infecciones del torrente sangu\u00edneo asociadas a los cat\u00e9teres son un problema cl\u00ednico importante ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eu.bd.com\/iv-news\/es\/novedades-e-innovacion\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\/\" \/>\n<meta property=\"og:site_name\" content=\"BD IV News\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-27T00:00:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-27T08:21:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2021\/09\/ART2_BD-41680-OCT-release-BD-IV-News-VA-Compl-2_IMAGE.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Camille Suarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camille Suarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/es\\\/novedades-e-innovacion\\\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/es\\\/novedades-e-innovacion\\\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\\\/\"},\"author\":{\"name\":\"Camille Suarez\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/person\\\/133274b3c3f2b1e2a25492760340ccf2\"},\"headline\":\"C\u00f3mo las mejores pr\u00e1cticas en el acceso vascular pueden ayudar a fomentar una cultura de seguridad y prevenci\u00f3n de infecciones\",\"datePublished\":\"2021-07-27T00:00:04+00:00\",\"dateModified\":\"2022-07-27T08:21:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/es\\\/novedades-e-innovacion\\\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\\\/\"},\"wordCount\":366,\"publisher\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/es\\\/novedades-e-innovacion\\\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/ART2_BD-41680-OCT-release-BD-IV-News-VA-Compl-2_IMAGE.jpeg\",\"articleSection\":[\"Novedades e innovaci\u00f3n\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/es\\\/novedades-e-innovacion\\\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\\\/\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/es\\\/novedades-e-innovacion\\\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\\\/\",\"name\":\"C\u00f3mo las mejores pr\u00e1cticas en el acceso vascular pueden ayudar a prevenir de infecciones\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/es\\\/novedades-e-innovacion\\\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/es\\\/novedades-e-innovacion\\\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/ART2_BD-41680-OCT-release-BD-IV-News-VA-Compl-2_IMAGE.jpeg\",\"datePublished\":\"2021-07-27T00:00:04+00:00\",\"dateModified\":\"2022-07-27T08:21:04+00:00\",\"description\":\"\u00bfSab\u00eda que las infecciones del torrente sangu\u00edneo asociadas a los cat\u00e9teres son un problema cl\u00ednico importante ?\",\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/es\\\/novedades-e-innovacion\\\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/es\\\/novedades-e-innovacion\\\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/ART2_BD-41680-OCT-release-BD-IV-News-VA-Compl-2_IMAGE.jpeg\",\"contentUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/ART2_BD-41680-OCT-release-BD-IV-News-VA-Compl-2_IMAGE.jpeg\",\"width\":1000,\"height\":667},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#website\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/\",\"name\":\"BD IV News\",\"description\":\"Your source of information on intravenous therapy, medication delivery and vascular access management.\",\"publisher\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#organization\",\"name\":\"BD IV News\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/BD-Master-Logo-on-Warm-White-512X512px.png\",\"contentUrl\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/BD-Master-Logo-on-Warm-White-512X512px.png\",\"width\":512,\"height\":512,\"caption\":\"BD IV News\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eu.bd.com\\\/iv-news\\\/#\\\/schema\\\/person\\\/133274b3c3f2b1e2a25492760340ccf2\",\"name\":\"Camille Suarez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g\",\"caption\":\"Camille Suarez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo las mejores pr\u00e1cticas en el acceso vascular pueden ayudar a prevenir de infecciones","description":"\u00bfSab\u00eda que las infecciones del torrente sangu\u00edneo asociadas a los cat\u00e9teres son un problema cl\u00ednico importante ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eu.bd.com\/iv-news\/es\/novedades-e-innovacion\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\/","og_locale":"en_GB","og_type":"article","og_title":"C\u00f3mo las mejores pr\u00e1cticas en el acceso vascular pueden ayudar a prevenir de infecciones","og_description":"\u00bfSab\u00eda que las infecciones del torrente sangu\u00edneo asociadas a los cat\u00e9teres son un problema cl\u00ednico importante ?","og_url":"https:\/\/eu.bd.com\/iv-news\/es\/novedades-e-innovacion\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\/","og_site_name":"BD IV News","article_published_time":"2021-07-27T00:00:04+00:00","article_modified_time":"2022-07-27T08:21:04+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2021\/09\/ART2_BD-41680-OCT-release-BD-IV-News-VA-Compl-2_IMAGE.jpeg","type":"image\/jpeg"}],"author":"Camille Suarez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Camille Suarez","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eu.bd.com\/iv-news\/es\/novedades-e-innovacion\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\/#article","isPartOf":{"@id":"https:\/\/eu.bd.com\/iv-news\/es\/novedades-e-innovacion\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\/"},"author":{"name":"Camille Suarez","@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/person\/133274b3c3f2b1e2a25492760340ccf2"},"headline":"C\u00f3mo las mejores pr\u00e1cticas en el acceso vascular pueden ayudar a fomentar una cultura de seguridad y prevenci\u00f3n de infecciones","datePublished":"2021-07-27T00:00:04+00:00","dateModified":"2022-07-27T08:21:04+00:00","mainEntityOfPage":{"@id":"https:\/\/eu.bd.com\/iv-news\/es\/novedades-e-innovacion\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\/"},"wordCount":366,"publisher":{"@id":"https:\/\/eu.bd.com\/iv-news\/#organization"},"image":{"@id":"https:\/\/eu.bd.com\/iv-news\/es\/novedades-e-innovacion\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2021\/09\/ART2_BD-41680-OCT-release-BD-IV-News-VA-Compl-2_IMAGE.jpeg","articleSection":["Novedades e innovaci\u00f3n"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/eu.bd.com\/iv-news\/es\/novedades-e-innovacion\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\/","url":"https:\/\/eu.bd.com\/iv-news\/es\/novedades-e-innovacion\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\/","name":"C\u00f3mo las mejores pr\u00e1cticas en el acceso vascular pueden ayudar a prevenir de infecciones","isPartOf":{"@id":"https:\/\/eu.bd.com\/iv-news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eu.bd.com\/iv-news\/es\/novedades-e-innovacion\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\/#primaryimage"},"image":{"@id":"https:\/\/eu.bd.com\/iv-news\/es\/novedades-e-innovacion\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2021\/09\/ART2_BD-41680-OCT-release-BD-IV-News-VA-Compl-2_IMAGE.jpeg","datePublished":"2021-07-27T00:00:04+00:00","dateModified":"2022-07-27T08:21:04+00:00","description":"\u00bfSab\u00eda que las infecciones del torrente sangu\u00edneo asociadas a los cat\u00e9teres son un problema cl\u00ednico importante ?","inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eu.bd.com\/iv-news\/es\/novedades-e-innovacion\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/eu.bd.com\/iv-news\/es\/novedades-e-innovacion\/como-las-mejores-practicas-en-el-acceso-vascular-pueden-ayudar-a-fomentar-una-cultura-de-seguridad-y-prevencion-de-infecciones\/#primaryimage","url":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2021\/09\/ART2_BD-41680-OCT-release-BD-IV-News-VA-Compl-2_IMAGE.jpeg","contentUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2021\/09\/ART2_BD-41680-OCT-release-BD-IV-News-VA-Compl-2_IMAGE.jpeg","width":1000,"height":667},{"@type":"WebSite","@id":"https:\/\/eu.bd.com\/iv-news\/#website","url":"https:\/\/eu.bd.com\/iv-news\/","name":"BD IV News","description":"Your source of information on intravenous therapy, medication delivery and vascular access management.","publisher":{"@id":"https:\/\/eu.bd.com\/iv-news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eu.bd.com\/iv-news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/eu.bd.com\/iv-news\/#organization","name":"BD IV News","url":"https:\/\/eu.bd.com\/iv-news\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/logo\/image\/","url":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2024\/04\/BD-Master-Logo-on-Warm-White-512X512px.png","contentUrl":"https:\/\/eu.bd.com\/iv-news\/wp-content\/uploads\/2024\/04\/BD-Master-Logo-on-Warm-White-512X512px.png","width":512,"height":512,"caption":"BD IV News"},"image":{"@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/eu.bd.com\/iv-news\/#\/schema\/person\/133274b3c3f2b1e2a25492760340ccf2","name":"Camille Suarez","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f50a86470bf0edfb5227a77db11a6f6ab98f270489a78660886c4d7bf008f2bd?s=96&d=mm&r=g","caption":"Camille Suarez"}}]}},"lang":"es","translations":{"es":3707},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts\/3707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/comments?post=3707"}],"version-history":[{"count":5,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts\/3707\/revisions"}],"predecessor-version":[{"id":4539,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/posts\/3707\/revisions\/4539"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/media\/3708"}],"wp:attachment":[{"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/media?parent=3707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/categories?post=3707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eu.bd.com\/iv-news\/wp-json\/wp\/v2\/tags?post=3707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}